{"id":11698,"date":"2010-03-14T11:34:43","date_gmt":"2010-03-14T10:34:43","guid":{"rendered":"http:\/\/www.mixcarteles.com\/cartelesmix\/?p=11698"},"modified":"2017-11-10T07:25:42","modified_gmt":"2017-11-10T07:25:42","slug":"terror-from-the-year-5000-1958","status":"publish","type":"post","link":"https:\/\/cartelesmix.com\/2020carteles\/terror-from-the-year-5000-1958\/","title":{"rendered":"El terror del a\u00f1o 5000 (Terror from the Year 5000) (1958)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-11698","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/posts\/11698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/comments?post=11698"}],"version-history":[{"count":1,"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/posts\/11698\/revisions"}],"predecessor-version":[{"id":101159,"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/posts\/11698\/revisions\/101159"}],"wp:attachment":[{"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/media?parent=11698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/categories?post=11698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/tags?post=11698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}