{"id":11727,"date":"2010-03-14T11:57:17","date_gmt":"2010-03-14T10:57:17","guid":{"rendered":"http:\/\/www.mixcarteles.com\/cartelesmix\/?p=11727"},"modified":"2017-11-10T07:25:39","modified_gmt":"2017-11-10T07:25:39","slug":"the-blonde-captive-the-blonde-captive","status":"publish","type":"post","link":"https:\/\/cartelesmix.com\/2020carteles\/the-blonde-captive-the-blonde-captive\/","title":{"rendered":"The Blonde captive (The Blonde captive) (1931)"},"content":{"rendered":"<p><a href=\"http:\/\/cartelesmix.es\/images\/CartelesB\/blondecaptive3101.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-31005\" title=\"blondecaptive3101\" src=\"http:\/\/cartelesmix.es\/images\/CartelesB\/blondecaptive3101-156x239.jpg\" alt=\"\" width=\"156\" height=\"239\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-11727","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/posts\/11727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/comments?post=11727"}],"version-history":[{"count":1,"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/posts\/11727\/revisions"}],"predecessor-version":[{"id":101132,"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/posts\/11727\/revisions\/101132"}],"wp:attachment":[{"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/media?parent=11727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/categories?post=11727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/tags?post=11727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}