{"id":11751,"date":"2010-03-14T12:03:23","date_gmt":"2010-03-14T11:03:23","guid":{"rendered":"http:\/\/www.mixcarteles.com\/cartelesmix\/?p=11751"},"modified":"2017-11-10T07:25:37","modified_gmt":"2017-11-10T07:25:37","slug":"the-deep-blue-sea-the-deep-blue-sea-1955","status":"publish","type":"post","link":"https:\/\/cartelesmix.com\/2020carteles\/the-deep-blue-sea-the-deep-blue-sea-1955\/","title":{"rendered":"The Deep Blue Sea (The Deep Blue Sea) (1955)"},"content":{"rendered":"<p><a href=\"http:\/\/cartelesmix.es\/images\/CartelesD\/deepbluesea5501.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-64089\" title=\"deepbluesea5501\" src=\"http:\/\/cartelesmix.es\/images\/CartelesD\/deepbluesea5501-163x240.jpg\" alt=\"\" width=\"163\" height=\"240\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-11751","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/posts\/11751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/comments?post=11751"}],"version-history":[{"count":1,"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/posts\/11751\/revisions"}],"predecessor-version":[{"id":101114,"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/posts\/11751\/revisions\/101114"}],"wp:attachment":[{"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/media?parent=11751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/categories?post=11751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/tags?post=11751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}