{"id":11757,"date":"2010-03-14T12:04:43","date_gmt":"2010-03-14T11:04:43","guid":{"rendered":"http:\/\/www.mixcarteles.com\/cartelesmix\/?p=11757"},"modified":"2017-11-10T07:25:36","modified_gmt":"2017-11-10T07:25:36","slug":"the-dragon-house-the-dragon-house-2006","status":"publish","type":"post","link":"https:\/\/cartelesmix.com\/2020carteles\/the-dragon-house-the-dragon-house-2006\/","title":{"rendered":"The dragon house (The dragon house) (2006)"},"content":{"rendered":"<p><a href=\"http:\/\/cartelesmix.es\/images\/CartelesD\/dragonhouse0601.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-66767\" title=\"dragonhouse0601\" src=\"http:\/\/cartelesmix.es\/images\/CartelesD\/dragonhouse0601-169x240.jpg\" alt=\"\" width=\"169\" height=\"240\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-11757","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/posts\/11757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/comments?post=11757"}],"version-history":[{"count":1,"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/posts\/11757\/revisions"}],"predecessor-version":[{"id":101109,"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/posts\/11757\/revisions\/101109"}],"wp:attachment":[{"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/media?parent=11757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/categories?post=11757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cartelesmix.com\/2020carteles\/wp-json\/wp\/v2\/tags?post=11757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}